{"id":1520,"date":"2024-12-12T11:07:29","date_gmt":"2024-12-12T03:07:29","guid":{"rendered":"https:\/?post_type=product&#038;p=1520"},"modified":"2025-09-02T10:06:10","modified_gmt":"2025-09-02T02:06:10","slug":"au204","status":"publish","type":"product","link":"https:\/\/www.apuvan.ru\/it\/products\/au204\/","title":{"rendered":"AU204 Portasciugamani riscaldato UV | Scaffale in ceramica | Controllo intelligente a sfioramento | Sterilizzazione UV | Montaggio a parete | Per piccoli bagni moderni"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Elevate l'igiene del bagno con questo intelligente portasciugamani riscaldato dotato di tecnologia germicida UV-C avanzata. Grazie alla sterilizzazione a raggi ultravioletti con lunghezza d'onda di 280 nm, il sistema elimina il 99,9% di batteri, muffe e virus e asciuga efficacemente gli asciugamani grazie alla convezione termica ottimizzata. Il piano d'appoggio integrato in ceramica composita con finitura in pietra naturale offre uno spazio resistente all'acqua per gli articoli da toilette e gli oggetti essenziali per il bagno. Caratterizzata da un design verticale efficiente dal punto di vista dello spazio e da un grado di impermeabilit\u00e0 IPX4, questa unit\u00e0 a doppia funzione combina la protezione antimicrobica con la funzionalit\u00e0 organizzativa per bagni che vanno dalle sale da bagno compatte alle suite padronali.<\/p>\n<p>Dimensioni: H810*W460*D130<br \/>\nPotenza: 100W<\/p>","protected":false},"featured_media":2235,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[209],"product_cat":[27,69,75],"product_tag":[714,719,694,700,708,695,691],"class_list":{"0":"post-1520","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-apuvan","7":"product_cat-all","8":"product_cat-heated-towel-rail","9":"product_cat-radiance-collection","10":"product_tag-hot-sale","11":"product_tag-brushed-copper-towel-rail","12":"product_tag-heated-rack-for-small-bathroom","13":"product_tag-plug-in-electric-towel-rack","14":"product_tag-roca-heated-towel-rail-for-bathroom","15":"product_tag-smart-heated-towel-rack","16":"product_tag-villa-heated-towel-rail","18":"first","19":"instock","20":"shipping-taxable","21":"purchasable","22":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/www.apuvan.ru\/it\/wp-json\/wp\/v2\/product\/1520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apuvan.ru\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.apuvan.ru\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apuvan.ru\/it\/wp-json\/wp\/v2\/comments?post=1520"}],"version-history":[{"count":1,"href":"https:\/\/www.apuvan.ru\/it\/wp-json\/wp\/v2\/product\/1520\/revisions"}],"predecessor-version":[{"id":3905,"href":"https:\/\/www.apuvan.ru\/it\/wp-json\/wp\/v2\/product\/1520\/revisions\/3905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apuvan.ru\/it\/wp-json\/wp\/v2\/media\/2235"}],"wp:attachment":[{"href":"https:\/\/www.apuvan.ru\/it\/wp-json\/wp\/v2\/media?parent=1520"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.apuvan.ru\/it\/wp-json\/wp\/v2\/product_brand?post=1520"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.apuvan.ru\/it\/wp-json\/wp\/v2\/product_cat?post=1520"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.apuvan.ru\/it\/wp-json\/wp\/v2\/product_tag?post=1520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}